{"id":1768,"date":"2016-06-02T15:37:05","date_gmt":"2016-06-02T13:37:05","guid":{"rendered":"http:\/\/www.stilum.com\/en\/?post_type=portfolio&#038;p=1768"},"modified":"2022-07-27T08:15:19","modified_gmt":"2022-07-27T06:15:19","slug":"horizontal-bar-supra1","status":"publish","type":"portfolio","link":"https:\/\/www.stilum.com\/en\/produkte\/horizontal-bar-supra1\/","title":{"rendered":"Horizontal Bar &#8220;Supra1&#8221;"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-fo7w7s-e91e235cb5587d1a0c0d535cb04341d2\">\n.flex_column.av-fo7w7s-e91e235cb5587d1a0c0d535cb04341d2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-fo7w7s-e91e235cb5587d1a0c0d535cb04341d2 av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-animated-generic left-to-right av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-e09jlk-fdb364f9b28b83b849a2c761c7ad8bce\">\n#top .avia-gallery.av-e09jlk-fdb364f9b28b83b849a2c761c7ad8bce .avia-gallery-thumb a{\nwidth:33.3333%;\n}\n<\/style>\n<div  class='avia-gallery av-e09jlk-fdb364f9b28b83b849a2c761c7ad8bce avia_animate_when_visible  avia-builder-el-1  avia-builder-el-no-sibling  avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.stilum.com\/en\/produkte\/horizontal-bar-supra1\/\"><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-1030x687.jpg\" data-srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-1030x687.jpg 1030w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-300x200.jpg 300w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-705x470.jpg 705w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-450x300.jpg 450w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-onclick='1' title='horizontal-bar-supra1' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22334 avia-img-lazy-loading-not-22334\"  width=\"495\" height=\"400\" src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg\" title='horizontal-bar-supra1' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-1030x687.jpg\" data-srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-1030x687.jpg 1030w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-300x200.jpg 300w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-705x470.jpg 705w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-450x300.jpg 450w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg' class='first_thumb lightbox ' data-onclick='1' title='horizontal-bar-supra1'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22334 avia-img-lazy-loading-not-22334\"   src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg\" width=\"495\" height=\"400\"  title='horizontal-bar-supra1' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-22334 avia-img-lazy-loading-22334\"  width=\"495\" height=\"400\" src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg\" title='horizontal-bar-supra1' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-1030x687.jpg\" data-srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-1030x687.jpg 1030w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-300x200.jpg 300w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-705x470.jpg 705w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-450x300.jpg 450w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-495x400.jpg' class='lightbox ' data-onclick='2' title='Horizontal Bar Supra1 with climbing Kid'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-14027 avia-img-lazy-loading-not-14027\"   src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-495x400.jpg\" width=\"495\" height=\"400\"  title='Horizontal Bar Supra1 with climbing Kid' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-14027 avia-img-lazy-loading-14027\"  width=\"495\" height=\"400\" src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-495x400.jpg\" title='Horizontal Bar Supra1 with climbing Kid' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo2-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-1030x687.jpg\" data-srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-1030x687.jpg 1030w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-300x200.jpg 300w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-705x470.jpg 705w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-450x300.jpg 450w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3.jpg 1200w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" data-rel='gallery-1' data-prev-img='https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-495x400.jpg' class='lightbox ' data-onclick='3' title='Horizontal Bar Supra1 CloseUp'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-14029 avia-img-lazy-loading-not-14029\"   src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-495x400.jpg\" width=\"495\" height=\"400\"  title='Horizontal Bar Supra1 CloseUp' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-14029 avia-img-lazy-loading-14029\"  width=\"495\" height=\"400\" src=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-495x400.jpg\" title='Horizontal Bar Supra1 CloseUp' alt='' srcset=\"https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-495x400.jpg 495w, https:\/\/www.stilum.com\/wp-content\/uploads\/horizontal-bar-supra1-stilum_photo3-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-calgrc-fc55ba77d4592bb5c5fb3bde63fda48e\">\n.flex_column.av-calgrc-fc55ba77d4592bb5c5fb3bde63fda48e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-calgrc-fc55ba77d4592bb5c5fb3bde63fda48e av_one_half  avia-builder-el-2  el_after_av_one_half  avia-builder-el-last  flex_column_div av-animated-generic right-to-left av-zero-column-padding  '     ><p><div  class='togglecontainer av-amlm4o-4078afb778936834a92fd62352bf37b6  avia-builder-el-3  el_before_av_hr  avia-builder-el-first  toggle_close_all' >\n<section class='av_toggle_section av-8rohqg-4a458c485c54c5d74ceb36709d6c6df8'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  activeTitle av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"General Information\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: General Information\" data-aria_expanded=\"Click to collapse: General Information\">General Information<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  active_tc av-title-above' style='display:block;' ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>Neither a schoolyard, nor a fitness trail nor a playground is complete without a <strong>horizontal bar<\/strong>. Easy apparatuses are best suited to burn energy. Children, in a first step, learn about gymnastics and <strong>playfully train<\/strong> their body control. Adults can train their muscels effectively by a variety of exercises ranging from light warm-ups to serious strengthening exercises.<\/p>\n<p>Note: Supra1 is available with an installation depth of 150 ( ID150 ) and 450 mm ( ID450 ).<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-pi8x4-7fe41d8537c92973fe129e0ad1e7bf90'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"Product Data\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Product Data\" data-aria_expanded=\"Click to collapse: Product Data\">Product Data<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><table>\n<tbody>\n<tr>\n<td>Material:<\/td>\n<td>Stainless steel<\/td>\n<\/tr>\n<tr>\n<td>ID 150 Item No.:<\/td>\n<td>551514401<\/td>\n<\/tr>\n<tr>\n<td>ID 450 Item No.:<\/td>\n<td>551514402<\/td>\n<\/tr>\n<tr>\n<td>Equipment dimensions:<\/td>\n<td>1510 x 120 x 1830 mm<\/td>\n<\/tr>\n<tr>\n<td>Maximum height of fall:<\/td>\n<td>1000 mm<\/td>\n<\/tr>\n<tr>\n<td>Minimum space:<\/td>\n<td>4000 x 3000 mm<\/td>\n<\/tr>\n<tr>\n<td>Safety surfacing area:<\/td>\n<td>10,32 m\u00b2<\/td>\n<\/tr>\n<tr>\n<td>Required safety slabs:<\/td>\n<td>12,00 m\u00b2<\/td>\n<\/tr>\n<tr>\n<td>Safety:<\/td>\n<td>DIN EN 1176<\/td>\n<\/tr>\n<tr>\n<td>Installation:<\/td>\n<td>with high impact dowels<\/td>\n<\/tr>\n<tr>\n<td>Age rating:<\/td>\n<td>from 6 years<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>All rights and product modifications reserved.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-5p30eg-8ffe5fefa84eb63f0fbda68b299195b2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-3' data-fake-id='#toggle-id-3' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3' data-slide-speed=\"200\" data-title=\"Downloads\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Downloads\" data-aria_expanded=\"Click to collapse: Downloads\">Downloads<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' aria-labelledby='toggle-toggle-id-3' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p><strong>Supra1 with 150mm installation depth<\/strong><\/p>\n<ul>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal bar-stilum_551514401_mounting.pdf\">Mounting Instruction | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal bar-stilum_551514401_maintenance.pdf\">Maintenance Instruction | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal-bar-stilum_551514401_data-sheet.pdf\">Data sheet | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-reck-stilum_551514401_FP.DWG\">Foundation plan | DWG<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-reck-stilum_551514401_DS.DWG\">Safety area | DWG<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-reck-stilum_551514401_Zertifikat.pdf\">Certificate | PDF<\/a><\/li>\n<\/ul>\n<p><strong>Supra1 with 450mm installation depth<\/strong><\/p>\n<ul>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal bar-stilum_551514402_mounting.pdf\">Mounting Instruction | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal bar-stilum_551514402_maintenance.pdf\">Maintenance Instruction | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-horizontal bar-stilum_551514402_datasheet.pdf\">Data sheet | PDF<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-reck-stilum_551514402_DS.DWG\">Safety area | DWG<\/a><\/li>\n<li><a href=\"\/wp-content\/uploads\/supra1-reck-stilum_551514402_Zertifikat.pdf\">Certificate | PDF<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/section>\n<\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4vzzi0-eeea78718fb0ed7654506c6c88b323b8\">\n#top .hr.hr-invisible.av-4vzzi0-eeea78718fb0ed7654506c6c88b323b8{\nheight:12px;\n}\n<\/style>\n<div  class='hr av-4vzzi0-eeea78718fb0ed7654506c6c88b323b8 hr-invisible  avia-builder-el-4  el_after_av_toggle_container  el_before_av_button_big  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-5  el_after_av_hr  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2h29qw-829317f7de1cae8b1eba8b6f5f1f9783\">\n#top #wrap_all .avia-button.av-2h29qw-829317f7de1cae8b1eba8b6f5f1f9783{\nbackground-color:#555555;\nborder-color:#555555;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-2h29qw-829317f7de1cae8b1eba8b6f5f1f9783:hover{\nbackground-color:#719430;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/www.stilum.com\/en\/contact\/' class='avia-button avia-button-fullwidth av-2h29qw-829317f7de1cae8b1eba8b6f5f1f9783 avia-icon_select-yes-left-icon avia-color-custom'   aria-label=\"Product Request\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue83c' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Product Request<\/span><div class='av-button-description av-button-description-below'><p>Ask for price and delivery time<\/p>\n<\/div><\/a><\/div><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":9258,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[53],"class_list":["post-1768","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-sports-equipment"],"_links":{"self":[{"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/portfolio\/1768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/comments?post=1768"}],"version-history":[{"count":4,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/portfolio\/1768\/revisions"}],"predecessor-version":[{"id":2753,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/portfolio\/1768\/revisions\/2753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/media\/9258"}],"wp:attachment":[{"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/media?parent=1768"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/tags?post=1768"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.stilum.com\/en\/wp-json\/wp\/v2\/portfolio_entries?post=1768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}